{"id":8381,"date":"2022-09-13T16:34:27","date_gmt":"2022-09-13T19:34:27","guid":{"rendered":"https:\/\/www.flane.com.pa\/blog\/?p=8381"},"modified":"2024-09-20T11:00:45","modified_gmt":"2024-09-20T14:00:45","slug":"ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros","status":"publish","type":"post","link":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/","title":{"rendered":"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span data-contrast=\"auto\">Nos \u00faltimos anos, vimos o cen\u00e1rio de amea\u00e7as digitais se tornar cada vez mais sofisticado. Os cibercriminosos est\u00e3o aumentando mais suas atividades, incapacitando governos e empresas, com os lucros desses ataques subindo. De acordo com o estudo\u00a0<\/span><span data-contrast=\"none\">Percep\u00e7\u00e3o do Risco Cibern\u00e9tico na Am\u00e9rica Latina em tempos de COVID-19<\/span><span data-contrast=\"auto\">, conduzido pela Marsh e encomendado pela Microsoft, apenas 16% das empresas entrevistadas aumentaram seu or\u00e7amento em seguran\u00e7a da informa\u00e7\u00e3o e ciberseguran\u00e7a durante a pandemia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Entre todas as ind\u00fastrias, os Servi\u00e7os Financeiros enfrentam os maiores desafios de seguran\u00e7a quando a frequ\u00eancia, a sofistica\u00e7\u00e3o e as recompensas dos crimes financeiros crescem. A ind\u00fastria de Servi\u00e7os Financeiros continua entre os tr\u00eas principais alvos de ataques de ransomware, como mostram os dados do\u00a0<\/span><span data-contrast=\"none\">Microsoft Digital Defense Report<\/span><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Eventos recentes nos mostraram como os cibercriminosos podem lan\u00e7ar facilmente um ataque de ransomware capaz de fechar empresas, impactar a economia e afetar a vida de milh\u00f5es de pessoas. Juntamente com setores da ind\u00fastria, como sa\u00fade, tecnologia da informa\u00e7\u00e3o e energia, o setor financeiro \u00e9 um componente-chave da infraestrutura cr\u00edtica e precisa de uma prote\u00e7\u00e3o robusta para se proteger de ataques, particularmente em mercados em desenvolvimento, como \u00e9 o caso da Am\u00e9rica Latina, em que, muitas vezes, ainda observamos uma falta de aten\u00e7\u00e3o at\u00e9 mesmo nas etapas fundamentais relacionadas \u00e0\u00a0ciberseguran\u00e7a.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para enfrentar esses desafios, as institui\u00e7\u00f5es financeiras precisam tomar v\u00e1rias medidas contra ataques virtuais. Habilitar a verifica\u00e7\u00e3o em\u00a0duas\u00a0etapas, aplicar o\u00a0princ\u00edpio\u00a0do\u00a0menor\u00a0privil\u00e9gio, garantir que os sistemas estejam protegidos com os patches e as atualiza\u00e7\u00f5es de seguran\u00e7a mais recentes e adotar solu\u00e7\u00f5es contra malwares s\u00e3o pr\u00e1ticas que ajudam com a seguran\u00e7a cibern\u00e9tica. Essas precau\u00e7\u00f5es s\u00e3o fundamentais, e podem at\u00e9 parecer \u00f3bvias, mas o n\u00famero crescente de ataques cibern\u00e9ticos\u00a0sugere que elas s\u00e3o muitas vezes ignoradas. H\u00e1 empresas que sequer est\u00e3o aproveitando as solu\u00e7\u00f5es j\u00e1 dispon\u00edveis \u2013 menos de 20% dos nossos clientes usam a verifica\u00e7\u00e3o em\u00a0duas\u00a0etapas, algo que \u00e9 gratuito e pode ser configurado para ser usado como padr\u00e3o.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3 aria-level=\"1\"><span data-contrast=\"none\">Proteja seus dados<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Sabemos que dados s\u00e3o muito valiosos, e \u00e0 medida em que eles se espalham cada vez mais para diferentes ferramentas, plataformas, dispositivos e nuvens, aumentam os riscos para a seguran\u00e7a e a conformidade com as leis. O surgimento de novas formas de pagamento \u2013 como o\u00a0<\/span><span data-contrast=\"none\">Pix no Brasil<\/span><span data-contrast=\"auto\">,\u00a0<\/span><span data-contrast=\"auto\">as\u00a0<\/span><span data-contrast=\"none\">Transfer\u00eancias 3.0 na Argentina<\/span><span data-contrast=\"auto\">\u00a0e o\u00a0<\/span><span data-contrast=\"none\">CoDi no M\u00e9xico<\/span><span data-contrast=\"auto\">\u00a0\u2013 tamb\u00e9m contribui para uma enorme quantidade de dados que as institui\u00e7\u00f5es financeiras podem usar. Mas entender esses dados e como proteg\u00ea-los durante todas as etapas \u00e9 algo necess\u00e1rio.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A intelig\u00eancia artificial (IA) e o machine learning (ML) est\u00e3o cada vez mais sofisticados e podem gerar insights a partir dos dados de uma organiza\u00e7\u00e3o. Bancos e institui\u00e7\u00f5es financeiras t\u00eam acesso a grandes volumes de dados sobre seus clientes e tecnologias como o\u00a0<\/span><a href=\"https:\/\/www.microsoft.com\/en-us\/industry\/financial-services\/microsoft-cloud-for-financial-services\"><span data-contrast=\"none\">Microsoft Cloud for Financial Services<\/span><\/a><span data-contrast=\"auto\">\u00a0est\u00e3o dispon\u00edveis para que as institui\u00e7\u00f5es aproveitem e tomem decis\u00f5es baseadas em dados com agilidade.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A governan\u00e7a de dados tamb\u00e9m desempenha um papel fundamental na ind\u00fastria de Servi\u00e7os Financeiros, uma vez que \u00e9 importante garantir a seguran\u00e7a e a privacidade dos dados. Um relat\u00f3rio da Morgan Stanley constatou que 17% dos CSOs (Chief Security Officers) identificaram a governan\u00e7a de dados como uma de suas tr\u00eas principais prioridades de seguran\u00e7a para 2021, um aumento de cinco pontos em rela\u00e7\u00e3o ao ano anterior. N\u00e3o \u00e9 surpresa, j\u00e1 que a sofistica\u00e7\u00e3o dos ataques, junto com a ampla ado\u00e7\u00e3o do trabalho remoto, aumentou as chances de um ataque, o que torna a governan\u00e7a de dados uma s\u00e9ria prioridade ao longo de 2022.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3 aria-level=\"1\"><span data-contrast=\"none\">Zero Trust como estrat\u00e9gia<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Proteger a identidade digital deve ser prioridade, e a estrat\u00e9gia Zero Trust desempenha um papel fundamental na prote\u00e7\u00e3o de dispositivos, usu\u00e1rios e dados, onde quer que eles estejam. A abordagem Zero Trust refere-se a uma mentalidade proativa que assume que toda atividade, mesmo por usu\u00e1rios conhecidos, pode ser uma tentativa de violar sistemas. Dado os riscos atuais para as empresas, tanto interna como externamente, o Zero Trust n\u00e3o \u00e9 mais apenas uma op\u00e7\u00e3o \u2014 \u00e9 um imperativo nos neg\u00f3cios.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Fatores como a forma com que organiza\u00e7\u00f5es armazenam seus dados ou por quanto tempo eles ficam salvos t\u00eam implica\u00e7\u00f5es que v\u00e3o al\u00e9m da conformidade e da seguran\u00e7a regulat\u00f3ria. De acordo com o Global Regulatory Outlook, da Duff &amp; Phelps, em 2021, quase um ter\u00e7o, ou 32% dos tomadores de decis\u00e3o de neg\u00f3cios no setor de servi\u00e7os financeiros previram que o custo total de conformidade seria superior a 5% de suas receitas. Para mitigar o risco em ambas as frentes, uma filosofia de Zero Trust deve estar no centro de todas as opera\u00e7\u00f5es da ind\u00fastria de Servi\u00e7os Financeiros.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Os princ\u00edpios do Zero Trust \u2014 verificar explicitamente, aplicar o\u00a0princ\u00edpio\u00a0do\u00a0menor\u00a0privil\u00e9gio\u00a0e sempre assumir que uma atividade suspeita pode ser uma viola\u00e7\u00e3o \u2014 estabelecem uma base para pr\u00e1ticas abrangentes de seguran\u00e7a e privacidade de dados, essenciais para a inova\u00e7\u00e3o. Elas tamb\u00e9m ajudam as organiza\u00e7\u00f5es a desenvolver um componente cr\u00edtico do sucesso: a resili\u00eancia.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3 aria-level=\"1\"><span data-contrast=\"none\">IA e automa\u00e7\u00e3o como aliados na seguran\u00e7a\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Uma abordagem integrada e completa, aliada a recursos de IA e de automa\u00e7\u00e3o, capacita as institui\u00e7\u00f5es financeiras a promover uma seguran\u00e7a de todos os \u00e2ngulos e em grande escala. O risco vem de muitas formas e uma abordagem mais simples \u00e9 uma vulnerabilidade que os cibercriminosos exploram. Al\u00e9m disso, uma estrat\u00e9gia para um amplo ecossistema de nuvens, plataformas e dispositivos fornece aos clientes a flexibilidade de escolha que eles tanto esperam.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Atualmente, os melhores sistemas de servi\u00e7os financeiros ajudam a proteger os dados desde o endpoint at\u00e9 a nuvem, abordando quest\u00f5es como a seguran\u00e7a, conformidade, gest\u00e3o de dispositivos e de identidades, assim como a gest\u00e3o da privacidade. \u00c9 o que estamos construindo com o\u00a0<\/span><a href=\"https:\/\/news.microsoft.com\/es-xl\/dibanka-revoluciona-los-creditos-de-libranza-con-digitalizacion-e-inteligencia-artificial-reduce-el-proceso-de-hasta-de-dias-a-solo-horas-y-beneficia-al-99-de-entidades-financieras-y-a-mas-de-125-00\/\"><b><span data-contrast=\"auto\">DiBanka<\/span><\/b><\/a><span data-contrast=\"auto\">, na Col\u00f4mbia, por exemplo. O ecossistema inovador para o bem-estar financeiro utiliza o Microsoft Azure, al\u00e9m de reconhecimento facial, para detectar o reconhecimento facial de seus afiliados, permitindo que todos os procedimentos sejam realizados de forma remota e segura.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Os recursos de IA e automa\u00e7\u00e3o podem capturar e rastrear amea\u00e7as internas ou externas \u00e0 organiza\u00e7\u00e3o. Uma das solu\u00e7\u00f5es voltadas \u00e0 privacidade e seguran\u00e7a \u00e9 o\u00a0<\/span><span data-contrast=\"none\">Gatekeeper<\/span><span data-contrast=\"auto\">, da Nuance,\u00a0<\/span><span data-contrast=\"none\">uma empresa l\u00edder em IA conversacional e intelig\u00eancia ambiental que foi recentemente adquirida pela Microsoft<\/span><span data-contrast=\"auto\">. O Gatekeeper \u00e9 uma solu\u00e7\u00e3o nativa de nuvem que aproveita redes neurais profundas e IA l\u00edder do setor para determinar uma decis\u00e3o \u00fanica e transparente de autentica\u00e7\u00e3o para cada engajamento. A plataforma analisa como a pessoa soa, como fala ou digita, e como se comporta, de forma transparente e em segundo plano de cada engajamento em todos os canais, enquanto verifica o dispositivo, a rede, a localiza\u00e7\u00e3o e outros fatores em busca de sinais de fraude.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Seguran\u00e7a, conformidade, inova\u00e7\u00e3o, privacidade, escolha e confian\u00e7a s\u00e3o temas interconectados e integrais para fortalecer a colabora\u00e7\u00e3o, a produtividade e a experi\u00eancia do usu\u00e1rio.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3 aria-level=\"1\"><span data-contrast=\"none\">Compromisso com a ciberseguran\u00e7a<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Para escalar e crescer com sucesso, as empresas de servi\u00e7os financeiros devem acelerar sua jornada rumo \u00e0 transforma\u00e7\u00e3o digital, entendendo o papel da ciberseguran\u00e7a dentro dela. Aquelas que usam as mais recentes tecnologias para gerenciar suas pol\u00edticas de seguran\u00e7a e conformidade se encontrar\u00e3o em uma posi\u00e7\u00e3o mais forte para enfrentar os desafios da gest\u00e3o de riscos e da conformidade. A Am\u00e9rica Latina est\u00e1 em um per\u00edodo crucial de oportunidades para impulsionar seu desenvolvimento. A ado\u00e7\u00e3o e a implementa\u00e7\u00e3o eficiente de ferramentas tecnol\u00f3gicas ser\u00e3o fundamentais na acelera\u00e7\u00e3o do crescimento presente e no futuro. Garantir essa jornada rumo \u00e0 maturidade digital ser\u00e1 ben\u00e9fico para todos os setores, empresas, organiza\u00e7\u00f5es e a comunidade, exigindo solu\u00e7\u00f5es constru\u00eddas tendo a ciberseguran\u00e7a como pilar fundamental e tamb\u00e9m uma prioridade constante.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<\/div><\/div><div class=\"w-separator size_small with_line width_default thick_1 style_solid color_border align_center\"><div class=\"w-separator-h\"><\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Por: <a href=\"https:\/\/news.microsoft.com\/pt-br\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/\">Microsoft Brasil<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Nos \u00faltimos anos, vimos o cen\u00e1rio de amea\u00e7as digitais se tornar cada vez mais sofisticado. Os cibercriminosos est\u00e3o aumentando mais suas atividades, incapacitando governos e empresas, com os lucros desses ataques subindo. De acordo com o estudo\u00a0Percep\u00e7\u00e3o do Risco Cibern\u00e9tico na Am\u00e9rica Latina em tempos de COVID-19, conduzido pela Marsh e encomendado pela Microsoft, apenas...","protected":false},"author":2,"featured_media":8382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1872,1882],"tags":[1848,1852,1906,1914,1916,2098,1856,2100],"class_list":["post-8381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cybersecurity-pt","category-microsoft-pt","tag-ciberseguranca-pt","tag-fast-lane-pt","tag-fast-lane-news-pt","tag-microsoft-pt","tag-news-pt","tag-proteja-seus-dados-pt","tag-seguranca-pt","tag-servicos-financeiros-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros - TechTalk powered by Fast Lane LATAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros - TechTalk powered by Fast Lane LATAM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/\" \/>\n<meta property=\"og:site_name\" content=\"TechTalk powered by Fast Lane LATAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FastLane.br\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-13T19:34:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T14:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2022\/09\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fast Lane TechTalk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FastLaneBr\" \/>\n<meta name=\"twitter:site\" content=\"@FastLaneBr\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fast Lane TechTalk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/\"},\"author\":{\"name\":\"Fast Lane TechTalk\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#\\\/schema\\\/person\\\/61993dd05b6199ccdb547e2504fae2aa\"},\"headline\":\"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros\",\"datePublished\":\"2022-09-13T19:34:27+00:00\",\"dateModified\":\"2024-09-20T14:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/\"},\"wordCount\":1427,\"publisher\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg\",\"keywords\":[\"Ciberseguran\u00e7a\",\"Fast Lane\",\"Fast Lane News\",\"Microsoft\",\"news\",\"Proteja seus dados\",\"seguran\u00e7a\",\"Servi\u00e7os Financeiros\"],\"articleSection\":[\"Cyber Security\",\"Microsoft\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/\",\"url\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/\",\"name\":\"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros - TechTalk powered by Fast Lane LATAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg\",\"datePublished\":\"2022-09-13T19:34:27+00:00\",\"dateModified\":\"2024-09-20T14:00:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg\",\"contentUrl\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg\",\"width\":1080,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/pt\\\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/\",\"name\":\"TechTalk powered by Fast Lane LATAM\",\"description\":\"Sharing ideas and knowledge on IT training and certification\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#organization\",\"name\":\"Fast Lane Brasil\",\"url\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/fast-lane-ng3.png\",\"contentUrl\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/fast-lane-ng3.png\",\"width\":209,\"height\":31,\"caption\":\"Fast Lane Brasil\"},\"image\":{\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FastLane.br\",\"https:\\\/\\\/x.com\\\/FastLaneBr\",\"https:\\\/\\\/www.instagram.com\\\/fastlane.br\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fastlanebr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/#\\\/schema\\\/person\\\/61993dd05b6199ccdb547e2504fae2aa\",\"name\":\"Fast Lane TechTalk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9943f25452073eb03e55f0e7e5c63ade3c1f051b706e0afa24bb9800c46ea9ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9943f25452073eb03e55f0e7e5c63ade3c1f051b706e0afa24bb9800c46ea9ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9943f25452073eb03e55f0e7e5c63ade3c1f051b706e0afa24bb9800c46ea9ce?s=96&d=mm&r=g\",\"caption\":\"Fast Lane TechTalk\"},\"sameAs\":[\"http:\\\/\\\/www.flane.com.pa\"],\"url\":\"https:\\\/\\\/www.flane.com.pa\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros - TechTalk powered by Fast Lane LATAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/","og_locale":"pt_BR","og_type":"article","og_title":"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros - TechTalk powered by Fast Lane LATAM","og_url":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/","og_site_name":"TechTalk powered by Fast Lane LATAM","article_publisher":"https:\/\/www.facebook.com\/FastLane.br","article_published_time":"2022-09-13T19:34:27+00:00","article_modified_time":"2024-09-20T14:00:45+00:00","og_image":[{"width":1080,"height":800,"url":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2022\/09\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg","type":"image\/jpeg"}],"author":"Fast Lane TechTalk","twitter_card":"summary_large_image","twitter_creator":"@FastLaneBr","twitter_site":"@FastLaneBr","twitter_misc":{"Escrito por":"Fast Lane TechTalk","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#article","isPartOf":{"@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/"},"author":{"name":"Fast Lane TechTalk","@id":"https:\/\/www.flane.com.pa\/blog\/#\/schema\/person\/61993dd05b6199ccdb547e2504fae2aa"},"headline":"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros","datePublished":"2022-09-13T19:34:27+00:00","dateModified":"2024-09-20T14:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/"},"wordCount":1427,"publisher":{"@id":"https:\/\/www.flane.com.pa\/blog\/#organization"},"image":{"@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2022\/09\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg","keywords":["Ciberseguran\u00e7a","Fast Lane","Fast Lane News","Microsoft","news","Proteja seus dados","seguran\u00e7a","Servi\u00e7os Financeiros"],"articleSection":["Cyber Security","Microsoft"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/","url":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/","name":"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros - TechTalk powered by Fast Lane LATAM","isPartOf":{"@id":"https:\/\/www.flane.com.pa\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#primaryimage"},"image":{"@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2022\/09\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg","datePublished":"2022-09-13T19:34:27+00:00","dateModified":"2024-09-20T14:00:45+00:00","breadcrumb":{"@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#primaryimage","url":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2022\/09\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg","contentUrl":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2022\/09\/Ciberseguranca-Um-imperativo-no-setor-de-servicos-financeiros.jpg","width":1080,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.flane.com.pa\/blog\/pt\/ciberseguranca-um-imperativo-no-setor-de-servicos-financeiros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.flane.com.pa\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"Ciberseguran\u00e7a: Um imperativo no setor de servi\u00e7os financeiros"}]},{"@type":"WebSite","@id":"https:\/\/www.flane.com.pa\/blog\/#website","url":"https:\/\/www.flane.com.pa\/blog\/","name":"TechTalk powered by Fast Lane LATAM","description":"Sharing ideas and knowledge on IT training and certification","publisher":{"@id":"https:\/\/www.flane.com.pa\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flane.com.pa\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.flane.com.pa\/blog\/#organization","name":"Fast Lane Brasil","url":"https:\/\/www.flane.com.pa\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.flane.com.pa\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2019\/10\/fast-lane-ng3.png","contentUrl":"https:\/\/www.flane.com.pa\/blog\/wp-content\/uploads\/2019\/10\/fast-lane-ng3.png","width":209,"height":31,"caption":"Fast Lane Brasil"},"image":{"@id":"https:\/\/www.flane.com.pa\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FastLane.br","https:\/\/x.com\/FastLaneBr","https:\/\/www.instagram.com\/fastlane.br\/","https:\/\/www.linkedin.com\/company\/fastlanebr"]},{"@type":"Person","@id":"https:\/\/www.flane.com.pa\/blog\/#\/schema\/person\/61993dd05b6199ccdb547e2504fae2aa","name":"Fast Lane TechTalk","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9943f25452073eb03e55f0e7e5c63ade3c1f051b706e0afa24bb9800c46ea9ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9943f25452073eb03e55f0e7e5c63ade3c1f051b706e0afa24bb9800c46ea9ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9943f25452073eb03e55f0e7e5c63ade3c1f051b706e0afa24bb9800c46ea9ce?s=96&d=mm&r=g","caption":"Fast Lane TechTalk"},"sameAs":["http:\/\/www.flane.com.pa"],"url":"https:\/\/www.flane.com.pa\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/posts\/8381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/comments?post=8381"}],"version-history":[{"count":1,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/posts\/8381\/revisions"}],"predecessor-version":[{"id":8383,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/posts\/8381\/revisions\/8383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/media\/8382"}],"wp:attachment":[{"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/media?parent=8381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/categories?post=8381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flane.com.pa\/blog\/wp-json\/wp\/v2\/tags?post=8381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}